{"id":88629,"date":"2025-09-09T09:49:58","date_gmt":"2025-09-09T07:49:58","guid":{"rendered":"https:\/\/langedykvintagewatches.com\/?post_type=product&#038;p=88629"},"modified":"2026-05-12T11:39:19","modified_gmt":"2026-05-12T09:39:19","slug":"rolex-datejust-16238-3","status":"publish","type":"product","link":"https:\/\/langedykvintagewatches.com\/nl\/product\/rolex-datejust-16238-3\/","title":{"rendered":"Rolex Oyster Perpetual Datejust Onyx 16238 1989 (Volledige Set)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Als je op zoek bent naar een bijzonder en iconisch horloge, dan kun je eigenlijk niet om de Rolex Datejust 16238 heen. Herkenbaar door de 18kt geelgouden Jubilee band met kroonsluiting, de volledig 18kt geelgouden kast (36mm) en fluted bezel. De Datejust 16238 is de ware belichaming van Rolex en haar exclusieve horloges. Het is niet voor niks dat het ontwerp van de Datejust sinds de introductie in 1945 haast ongewijzigd is gebleven. Zie jij jezelf al de show stelen met dit prachtige geelgouden Rolex horloge?<\/p>\n<p>De Rolex Datejust 16238 die wij aanbieden komt uit 1994 en loopt op het automatische 3135 uurwerk van Rolex. Daarnaast heeft dit horloge een prachtige Onyx wijzerplaat met een Arabische 6 &amp; 9 index en diamanten inlay. Deze Rolex Datejust 16238 uit 1994 is in mint conditie door de dikke kast, strakke bezel en stevige jubilee band. Het horloge komt met de originele doos, papieren en (handleiding)boekjes.<\/p>\n<p>Elk horloge uit onze collectie wordt geleverd met een certificaat van echtheid en 12 maanden garantie. Bij een watch only verstrekken wij onze eigen LVW-horloge box en certificaat van echtheid. Daarnaast worden al onze horloges kosteloos en verzekerd verstuurd.<\/p>\n<p>Ontvangt je graag extra informatie over dit horloge? Neem dan gerust telefonisch contact met ons op of stuur een e-mail. Wij proberen je aanvraag zo spoedig mogelijk te beantwoorden binnen 24 uur.<\/p>\n<p class=\"p1\">Bekijk ook onze volledige collectie Rolex <a href=\"https:\/\/langedykvintagewatches.com\/nl\/rolex-horloges\/datejust\/\"><span class=\"s1\">Datejust<\/span><\/a> horloges.<\/p>\n","protected":false},"featured_media":88949,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[480,1836,486,499,481,484,483,498,500],"product_tag":[],"class_list":{"0":"post-88629","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","5":"product_cat-heren-horloges","6":"product_cat-16238-nl","7":"product_cat-datejust","8":"product_cat-horloges","9":"product_cat-nieuw-binnen","10":"product_cat-rolex-horloges","11":"product_cat-rolex-nl-2","12":"product_cat-unisex-horloges","13":"product_cat-vrouwen-horloges","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/langedykvintagewatches.com\/nl\/wp-json\/wp\/v2\/product\/88629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/langedykvintagewatches.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/langedykvintagewatches.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/langedykvintagewatches.com\/nl\/wp-json\/wp\/v2\/media\/88949"}],"wp:attachment":[{"href":"https:\/\/langedykvintagewatches.com\/nl\/wp-json\/wp\/v2\/media?parent=88629"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/langedykvintagewatches.com\/nl\/wp-json\/wp\/v2\/product_brand?post=88629"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/langedykvintagewatches.com\/nl\/wp-json\/wp\/v2\/product_cat?post=88629"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/langedykvintagewatches.com\/nl\/wp-json\/wp\/v2\/product_tag?post=88629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}