{"id":56061,"date":"2024-03-12T05:12:02","date_gmt":"2024-03-08T15:49:59","guid":{"rendered":"https:\/\/langedykvintagewatches.com\/?post_type=product&#038;p=56061"},"modified":"2024-03-12T05:12:03","modified_gmt":"2024-03-12T05:12:03","slug":"rolex-datejust-16233-32","status":"publish","type":"product","link":"https:\/\/langedykvintagewatches.com\/de\/produkt\/rolex-datejust-16233-32\/","title":{"rendered":"Rolex Oyster Perpetual Datejust Black 16233 1990 (Vollst\u00e4ndiger Satz)"},"content":{"rendered":"<p>Von der kannelierten L\u00fcnette aus 18-kar\u00e4tigem Gold \u00fcber die 3-Stunden-Datumslupe mit Cyclops-Auge bis hin zur kunstvoll gestalteten Kombination aus Edelstahl und Gelbgold (18-kar\u00e4tig) ist die Rolex Datejust 16233 der wahre Inbegriff der ikonischen Rolex-Uhren. Dieses Modell erschien 1988 zum ersten Mal in den Juweliergesch\u00e4ften und wurde mit der neuen Referenznummer 16233&#8243; auf den neuesten Stand gebracht. Rolex ersetzte zum ersten Mal das \u00fcbliche Acrylglas und stattete die Datejust mit einem Saphirglas aus, was sie etwas moderner erscheinen l\u00e4sst.<\/p>\n<p>Die Datejust 16233 schreit wie kaum ein anderes Modell nach Rolex und wurde in unz\u00e4hligen Filmen und Fernsehserien zur ikonischen und stets erkennbaren Version der Uhr. Die Datejust 16233 ist ein Synonym f\u00fcr Luxus und verf\u00fcgt \u00fcber ein Automatikwerk des Kalibers 3135 mit der seiner Zeit vorausweisenden Quickset-Funktion f\u00fcr den sofortigen Datumswechsel. Das Rolex-Kaliber 3135 arbeitet mit 28.800 Schl\u00e4gen pro Stunde, was eine zuverl\u00e4ssige Gangreserve von 48 Stunden erm\u00f6glicht und dieses Datejust-Modell zu einem Muss f\u00fcr jeden Rolex-Liebhaber macht.<\/p>\n<p>Von Winston Churchill \u00fcber FDR bis hin zu James Bond &#8211; Rolex-Uhren aller Marken und Modelle sind f\u00fcr die einflussreichsten und innovativsten Menschen der Welt zu einem Symbol f\u00fcr Eleganz, Klasse und Pr\u00e4zisionsdesign geworden. Sie sind in der Tat eine zeitlose Armbanduhr, die mit der meisterhaften Handwerkskunst hergestellt wird, die Sie in einem Zeitmesser von h\u00f6chster Erbst\u00fcckqualit\u00e4t finden k\u00f6nnen. Erleben Sie den Unterschied in Klasse, Stil und Handwerkskunst, der mit der Rolex Datejust 16233 einhergeht, und entdecken Sie die wahre Vielseitigkeit an Ihrem Handgelenk.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rolex Oyster Perpetual Datejust Referenz 16233 aus dem Jahr 1990 mit komplettem Set. Die Datejust 16233 misst eine 36mm Gold und Edelstahl Geh\u00e4use, zweifarbige Jubilee Armband und kannelierte 18k Gold L\u00fcnette. Diese Datejust 16233 verf\u00fcgt \u00fcber ein Automatikwerk Kaliber 3135 mit einem Quickset-Datum-Funktion, eine Kratzfestigkeit Saphirglas und ein schwarzes Zifferblatt mit Tritium Zeiger.<\/p>\n<p>Jede Uhr, die von Langedyk Vintage Watches verkauft wird, wird mit einer LVW-Uhrenbox, einem Echtheitsbericht und einem kostenlosen weltweiten (versicherten) Versand geliefert. Dar\u00fcber hinaus gilt f\u00fcr jede gebrauchte Uhr unsere 12-monatige Garantie ab dem Kaufdatum.<\/p>\n<p>Wenn Sie Fragen haben oder zus\u00e4tzliche Informationen zu dieser Uhr erhalten m\u00f6chten, k\u00f6nnen Sie uns gerne telefonisch oder per E-Mail kontaktieren. Wir werden Ihre Anfrage so schnell wie m\u00f6glich beantworten.<\/p>\n<p>Werfen Sie auch einen Blick auf unsere komplette Kollektion von Rolex <a href=\"https:\/\/langedykvintagewatches.com\/de\/rolex-brands-de\/datejust-de\/\">Datejust<\/a> Uhren.<\/p>\n","protected":false},"featured_media":56294,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1928,2022,2023,1922,1909,1910,1915,1914,2021,2600],"product_tag":[],"class_list":["post-56061","product","type-product","status-publish","has-post-thumbnail","product_cat-16233-de","product_cat-armbanduhren","product_cat-damenuhren","product_cat-datejust-de","product_cat-herrenuhren","product_cat-neu-eingetroffen","product_cat-rolex-brands-de","product_cat-rolex-de","product_cat-unisex-armbanduhren","product_cat-verkaufte-uhren","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/langedykvintagewatches.com\/de\/wp-json\/wp\/v2\/product\/56061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/langedykvintagewatches.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/langedykvintagewatches.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/langedykvintagewatches.com\/de\/wp-json\/wp\/v2\/media\/56294"}],"wp:attachment":[{"href":"https:\/\/langedykvintagewatches.com\/de\/wp-json\/wp\/v2\/media?parent=56061"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/langedykvintagewatches.com\/de\/wp-json\/wp\/v2\/product_brand?post=56061"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/langedykvintagewatches.com\/de\/wp-json\/wp\/v2\/product_cat?post=56061"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/langedykvintagewatches.com\/de\/wp-json\/wp\/v2\/product_tag?post=56061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}